{"id":8171,"date":"2021-06-29T16:19:09","date_gmt":"2021-06-29T14:19:09","guid":{"rendered":"https:\/\/blog.federnshop.com\/verificacion-de-funcion-y-resistencia-para-resortes-de-compresion\/"},"modified":"2021-06-29T16:19:09","modified_gmt":"2021-06-29T14:19:09","slug":"verificacion-de-funcion-y-resistencia-para-resortes-de-compresion","status":"publish","type":"post","link":"https:\/\/blog.federnshop.com\/es\/verificacion-de-funcion-y-resistencia-para-resortes-de-compresion\/","title":{"rendered":"Verificaci\u00f3n de funci\u00f3n y resistencia para resortes de compresi\u00f3n"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\">Cada dise\u00f1o de resorte de un resorte de compresi\u00f3n consta de dos etapas<\/span> :<br \/>\n1. La prueba de funcionamiento, con la verificaci\u00f3n de las dimensiones, velocidad del resorte, fuerzas, recorrido del resorte y comportamiento vibratorio.<br \/>\n2. La prueba de resistencia, con la verificaci\u00f3n del cumplimiento de la tensi\u00f3n permisible o resistencia a la fatiga.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-716 size-large\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/\/GF_Druckfedern_technisch-1024x663.jpg\" alt=\"Explicaci\u00f3n de la f\u00f3rmula del resorte de compresi\u00f3n\" width=\"700\" height=\"453\" data-wp-pid=\"716\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/GF_Druckfedern_technisch-1024x663.jpg 1024w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/GF_Druckfedern_technisch-300x194.jpg 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/GF_Druckfedern_technisch-600x389.jpg 600w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/GF_Druckfedern_technisch-200x130.jpg 200w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/GF_Druckfedern_technisch-800x518.jpg 800w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/GF_Druckfedern_technisch.jpg 2001w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/h2>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/blog.federnshop.com\/es\/verificacion-de-funcion-y-resistencia-para-resortes-de-compresion\/#Prueba_de_funcion\" >Prueba de funci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/blog.federnshop.com\/es\/verificacion-de-funcion-y-resistencia-para-resortes-de-compresion\/#Prueba_de_fuerza\" >Prueba de fuerza<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Prueba_de_funcion\"><\/span>Prueba de funci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lo siguiente se aplica a los resortes de compresi\u00f3n cil\u00edndricos hechos de alambre con una secci\u00f3n transversal circular.<\/p>\n<p><span style=\"text-decoration: underline;\">Tasa de primavera<\/span> :<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8176 aligncenter\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federrate.png\" alt=\"Druckfeder Formel - Federrate\" width=\"155\" height=\"100\" data-wp-pid=\"737\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federrate.png 309w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federrate-300x194.png 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federrate-200x129.png 200w\" sizes=\"auto, (max-width: 155px) 100vw, 155px\" \/><\/p>\n<p style=\"text-align: left;\">de R = F \/ s se sigue &#8230;<\/p>\n<p><span style=\"text-decoration: underline;\">Fuerza de la primavera<\/span> :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8175 aligncenter\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federkraft.png\" alt=\"Druckfeder Formel - Federkraft\" width=\"158\" height=\"100\" data-wp-pid=\"736\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federkraft.png 315w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federkraft-300x190.png 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federkraft-200x127.png 200w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/p>\n<p>como &#8230;<\/p>\n<p><span style=\"text-decoration: underline;\">Recorrido de suspensi\u00f3n<\/span> :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8177 aligncenter\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federweg.png\" alt=\"Druckfeder Formel - Federweg\" width=\"173\" height=\"100\" data-wp-pid=\"738\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federweg.png 345w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federweg-300x174.png 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Federweg-200x116.png 200w\" sizes=\"auto, (max-width: 173px) 100vw, 173px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Prueba_de_fuerza\"><\/span>Prueba de fuerza<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Una vez determinadas las dimensiones del resorte, se debe verificar la resistencia. Para ello, se determina el esfuerzo cortante existente.<\/p>\n<p><span style=\"text-decoration: underline;\">Tensi\u00f3n por fuerza<\/span> :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8179 aligncenter\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Spannung-aus-Kraft.png\" alt=\"Druckfeder Formel - Spannung aus Kraft\" width=\"152\" height=\"100\" data-wp-pid=\"740\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Spannung-aus-Kraft.png 303w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Spannung-aus-Kraft-300x198.png 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Spannung-aus-Kraft-200x132.png 200w\" sizes=\"auto, (max-width: 152px) 100vw, 152px\" \/><\/p>\n<p><span style=\"text-decoration: underline;\">Tensi\u00f3n fuera de camino<\/span> :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8180 aligncenter\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Spannung-aus-Weg.png\" alt=\"Druckfeder Formel - Spannung aus Weg\" width=\"158\" height=\"100\" data-wp-pid=\"741\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Spannung-aus-Weg.png 316w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Spannung-aus-Weg-300x190.png 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Spannung-aus-Weg-200x127.png 200w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Mientras que el esfuerzo cortante \u01ae se usa para el dise\u00f1o de resortes con carga est\u00e1tica o cuasi est\u00e1tica, el esfuerzo cortante corregido \u01aek se aplica a los resortes cargados din\u00e1micamente. La distribuci\u00f3n del esfuerzo cortante en la secci\u00f3n transversal del alambre de un resorte es desigual. La tensi\u00f3n m\u00e1s alta se produce en el di\u00e1metro interior del resorte. Con el factor de correcci\u00f3n de tensi\u00f3n \u00abk\u00bb, que depende de la relaci\u00f3n de bobinado (relaci\u00f3n entre el di\u00e1metro medio \u00abD\u00bb y el tama\u00f1o de alambre \u00abd\u00bb) del resorte, se puede determinar aproximadamente la tensi\u00f3n m\u00e1s alta. Para resortes tensados din\u00e1micamente obtenemos:<\/p>\n<p><span style=\"text-decoration: underline;\">Esfuerzo cortante corregido<\/span> : \u01aek = k \u00b7 \u01ae<\/p>\n<p>donde se aplica k (seg\u00fan Bergstr\u00e4\u00dfer):<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8178 aligncenter\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_K-Wert-Bergstraesser.png\" alt=\"Druckfeder Formel - k-Wert nach Bergstr\u00e4sser\" width=\"198\" height=\"180\" data-wp-pid=\"739\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_K-Wert-Bergstraesser.png 440w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_K-Wert-Bergstraesser-300x273.png 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_K-Wert-Bergstraesser-200x182.png 200w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/p>\n<p>Ahora la comparaci\u00f3n se realiza con la tensi\u00f3n admisible. Esto se define de la siguiente manera:<\/p>\n<p><span style=\"text-decoration: underline;\">Voltaje admisible:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8181 aligncenter\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Zulaessige-Spannung.png\" alt=\"Druckfeder Formel - Zul\u00e4ssige Spannung\" width=\"178\" height=\"50\" data-wp-pid=\"742\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Zulaessige-Spannung.png 355w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Zulaessige-Spannung-300x85.png 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Zulaessige-Spannung-200x56.png 200w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8182 aligncenter\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Zulaessige-Spannung-bei-Blocklaenge.png\" alt=\"Druckfeder Formel - Zul\u00e4ssige Spannung bei Blockl\u00e4nge\" width=\"203\" height=\"50\" data-wp-pid=\"743\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Zulaessige-Spannung-bei-Blocklaenge.png 406w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Zulaessige-Spannung-bei-Blocklaenge-300x74.png 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Druckfeder_Formel_Zulaessige-Spannung-bei-Blocklaenge-200x49.png 200w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/p>\n<p>Los valores de la resistencia m\u00ednima a la tracci\u00f3n Rm dependen del grosor del alambre y se encuentran en las normas pertinentes.<a title=\"Federwerkstoffe\" href=\"https:\/\/blog.federnshop.com\/es\/propiedades-del-acero-para-muelles\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Materiales<\/a> encontrar. Como regla general, debe ser posible comprimir los resortes de compresi\u00f3n hasta la longitud del bloque, por lo que se debe tener en cuenta la tensi\u00f3n permitida para la longitud del bloque \u01aeczul. A<a href=\"https:\/\/blog.federnshop.com\/es\/tipos-de-resortes-de-compresion-de-tension\/\" target=\"_blank\" rel=\"noopener noreferrer\"> estr\u00e9s din\u00e1mico<\/a> Se debe determinar la tensi\u00f3n superior e inferior (\u01aek1 y \u01aek2) de la carrera correspondiente. La diferencia es el voltaje de carrera. Tanto la tensi\u00f3n superior como la tensi\u00f3n de carrera no deben superar los valores admisibles correspondientes. Estos son los diagramas de resistencia a la fatiga del<a title=\"DIN EN 13906-1\" href=\"http:\/\/www.beuth.de\/de\/norm\/din-en-13906-1\/189797622\" target=\"_blank\" rel=\"noopener noreferrer\"> EN 13906-1<\/a> para ser encontrado, o en<a title=\"Druckfedernberechnung WinFSB\" href=\"https:\/\/www.federnshop.com\/de\/produkte\/druckfedern\/berechnung.html\" target=\"_blank\" rel=\"noopener noreferrer\"> Programa de c\u00e1lculo Spring WinFSB<\/a> verificar (<a title=\"Lehrvideo Druckfedernberechnung mit WinFSB\" href=\"https:\/\/youtu.be\/EusjLYwYpLE\" target=\"_blank\" rel=\"noopener noreferrer\"> C\u00e1lculo de resorte de compresi\u00f3n de video con WinFSB<\/a> ). Si las tensiones resisten esta comparaci\u00f3n, el resorte es resistente a la fatiga con un ciclo de carga l\u00edmite de 10<sup> S\u00e9ptimo<\/sup><\/p>","protected":false},"excerpt":{"rendered":"<p>Cada dise\u00f1o de resorte de un resorte de compresi\u00f3n consta de dos etapas : 1. La prueba de funcionamiento, con la verificaci\u00f3n de las dimensiones, velocidad del resorte, fuerzas, recorrido del resorte y comportamiento vibratorio. 2. La prueba de resistencia,<\/p>\n","protected":false},"author":4,"featured_media":3815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[476,895,896,990],"tags":[2100,2097,1151,1900,660,2099,1492,821,601,2098,602,1432],"class_list":["post-8171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conocimiento","category-muelles-de-alambre","category-muelles-de-compresion","category-servicio-es","tag-calcular-la-primavera","tag-comportamiento-de-vibracion","tag-dauerfestigkeit-es","tag-diagrama-de-goodman","tag-druckfedern-es","tag-factor-de-correccion-de-tension-k","tag-federauslegung-es","tag-federnberechnung-es","tag-festigkeitsnachweis-es","tag-prueba-de-funcion","tag-schubspannung-es","tag-tasa-de-resorte"],"_links":{"self":[{"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/posts\/8171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/comments?post=8171"}],"version-history":[{"count":0,"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/posts\/8171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/media\/3815"}],"wp:attachment":[{"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/media?parent=8171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/categories?post=8171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.federnshop.com\/es\/wp-json\/wp\/v2\/tags?post=8171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}