{"id":8710,"date":"2024-08-18T11:37:27","date_gmt":"2024-08-18T09:37:27","guid":{"rendered":"https:\/\/blog.federnshop.com\/calcola-la-costante-della-molla\/"},"modified":"2024-08-19T10:42:44","modified_gmt":"2024-08-19T08:42:44","slug":"calcola-la-costante-della-molla","status":"publish","type":"post","link":"https:\/\/blog.federnshop.com\/it\/calcola-la-costante-della-molla\/","title":{"rendered":"Calcola la costante della molla"},"content":{"rendered":"<p>La costante della molla descrive at<a href=\"https:\/\/blog.federnshop.com\/druckfedern\/\"> Molle a compressione<\/a> ,<a href=\"https:\/\/blog.federnshop.com\/zugfedern\/\"> Molle a trazione<\/a> e<a href=\"https:\/\/blog.federnshop.com\/schenkelfedern-torsionsfedern\/\"> Molle a torsione<\/a> l&#8217;aumento in vigore rispetto al<a href=\"https:\/\/blog.federnshop.com\/federarbeit\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Corsa della sospensione<\/a> , oppure con molle di torsione in relazione all&#8217;angolo di rotazione. Si chiama anche<a href=\"https:\/\/blog.federnshop.com\/federrate-berechnen\/\"> Indice di rigidezza<\/a> , Durezza della molla o rigidit\u00e0 della molla e definisce la durezza di una molla. Con il<a href=\"https:\/\/blog.federnshop.com\/federkennlinie\/\"> Caratteristica primaverile<\/a> viene mostrato l&#8217;andamento di una costante elastica. La costante della molla \u00e8 lineare, ovvero il<a href=\"https:\/\/blog.federnshop.com\/federkraft-berechnen\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Forza della molla<\/a> aumenta uniformemente con il carico sulla molla, quindi la caratteristica della molla \u00e8 diritta (b.). Se invece la forza della molla aumenta in modo sproporzionato o sproporzionato all&#8217;aumentare del carico, allora si parla di caratteristica della molla progressiva (a.) o decrescente (c.). La costante della molla per le molle a compressione e le molle a trazione \u00e8 specificata nell&#8217;unit\u00e0 Newton\/millimetro e per le molle a torsione come la coppia della molla in Newton millimetri.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5340\" aria-describedby=\"caption-attachment-5340\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blog.federnshop.com\/federkennlinie\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1733 size-full\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Federkennlinien_600px.jpg\" alt=\"Caratteristiche primaverili\" width=\"600\" height=\"352\" data-wp-pid=\"1733\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Federkennlinien_600px.jpg 600w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Federkennlinien_600px-300x176.jpg 300w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Federkennlinien_600px-200x117.jpg 200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-5340\" class=\"wp-caption-text\">Caratteristiche primaverili<\/figcaption><\/figure>\n<p>Per la costante elastica con caratteristica elastica diritta vale quindi quanto segue:<\/p>\n<p>Molle a compressione e trazione<\/p>\n<p><strong><span class=\"katex-eq\" data-katex-display=\"false\">R = \\frac{F2-F1}{s2-s1}<\/span><\/strong><\/p>\n<p>Schenkelfedern<\/p>\n<p><strong><span class=\"katex-eq\" data-katex-display=\"false\">R = \\frac{M2-M1}{\\alpha2-\\alpha1}<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Formule per il calcolo della costante elastica per molle a compressione, molle a trazione e molle a torsione:<\/strong><\/p>\n<p>Formula molla molle a compressione costante (N\/mm) (<a href=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Gutekunst_Druckfedern_Formeln_2015.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"> Molle a compressione collezione Formula<\/a> )<\/p>\n<p><strong><span class=\"katex-eq\" data-katex-display=\"false\">R=\\frac{Gd^{4}}{8D^{3}n}<\/span><\/strong><\/p>\n<p>Formula molla molle a trazione costante (N\/mm) (<a href=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Gutekunst_Zugfedern_Formeln_2015.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"> Molle di estensione collezione Formula<\/a> )<\/p>\n<p><strong><span class=\"katex-eq\" data-katex-display=\"false\">R=\\frac{Gd^{4}}{8D^{3}n}=\\frac{F-F0}{s}<\/span><\/strong><\/p>\n<p>Molle a torsione con rapporto di coppia della molla Formula (Nmm) (<a href=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Gutekunst_Schenkelfedern_Formeln_2015.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"> Collezione formula molle a torsione<\/a> )<\/p>\n<p><strong><span class=\"katex-eq\" data-katex-display=\"false\">R_{M}=\\frac{M}{\\alpha}=\\frac{d^{4}E}{3667Dn}<\/span><\/strong><\/p>\n<p><em>Spiegazione della formula:<\/em><br \/>\n\u03b1 = angolo di rotazione (\u00b0)<br \/>\nd = diametro del filo (mm)<br \/>\nD = diametro medio bobina (mm)<br \/>\nE = modulo di elasticit\u00e0 (N\/mm\u00b2) (<a href=\"https:\/\/blog.federnshop.com\/federstahl\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Modulo E di diversi acciai per molle<\/a> )<br \/>\nF = forza della molla (N)<br \/>\nG = modulo di scorrimento e taglio (N \/ mm\u00b2) (<a href=\"https:\/\/blog.federnshop.com\/federstahl\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Modulo G realizzato con diversi acciai per molle<\/a> )<br \/>\nF0 = forza di precarico interna<br \/>\nM = coppia (Nmm)<br \/>\nn = numero di bobine resilienti (pezzi)<br \/>\nR = costante elastica (N\/mm)<br \/>\nRM = rapporto di coppia della molla (Nmm)<br \/>\ns = corsa della molla (mm)<\/p>\n<figure id=\"attachment_8719\" aria-describedby=\"caption-attachment-8719\" style=\"width: 236px\" class=\"wp-caption alignright\"><a href=\"https:\/\/de.wikipedia.org\/wiki\/Federkonstante\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2213 size-medium\" src=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/\/Zugversuch_Federn-236x300.jpg\" alt=\"Molle metalliche per prova di trazione - \u00a9 Von Menner - Wikipedia\" width=\"236\" height=\"300\" data-wp-pid=\"2213\" srcset=\"https:\/\/blog.federnshop.com\/wp-content\/uploads\/Zugversuch_Federn-236x300.jpg 236w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Zugversuch_Federn.jpg 600w, https:\/\/blog.federnshop.com\/wp-content\/uploads\/Zugversuch_Federn-157x200.jpg 157w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><\/a><figcaption id=\"caption-attachment-8719\" class=\"wp-caption-text\">Prova di trazione &#8211; \u00a9 Von Menner &#8211; Wikipedia<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>La costante della molla pu\u00f2 essere determinata anche mediante una prova di trazione. La molla viene allontanata con una forza (F) e la deflessione della molla \/<a href=\"https:\/\/blog.federnshop.com\/federarbeit\/\" target=\"_blank\" rel=\"noopener noreferrer\"> lavoro di primavera<\/a> (s2) misurato. Questo d\u00e0 la costante della molla in Newton\/millimetro.<\/p>\n<p><strong><span class=\"katex-eq\" data-katex-display=\"false\">R = \\frac{F}{s}<\/span><\/strong><\/p>\n<p>Tuttavia, questa prova di trazione deve essere eseguita con forze diverse per ottenere un risultato di misurazione accurato.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Ulteriori informazioni<\/em><\/p>\n<ul>\n<li><a href=\"https:\/\/www.federnshop.com\/de\/federberechnung-auswahl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Programma di calcolo delle molle Gutekunst WinFSB<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/blog.federnshop.com\/federkraft-berechnen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Calcola la forza della molla<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/blog.federnshop.com\/federarbeit\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lavoro primaverile<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/blog.federnshop.com\/federstahl\/\" target=\"_blank\" rel=\"noopener noreferrer\">Propriet\u00e0 dell&#8217;acciaio per molle<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/blog.federnshop.com\/federkennlinie\/\" target=\"_blank\" rel=\"noopener noreferrer\">Caratteristica della primavera<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La costante della molla descrive at Molle a compressione , Molle a trazione e Molle a torsione l&#8217;aumento in vigore rispetto al Corsa della sospensione , oppure con molle di torsione in relazione all&#8217;angolo di rotazione. Si chiama anche Indice<\/p>\n","protected":false},"author":4,"featured_media":8719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[470,882,883],"tags":[2232,2234,2231,2233,639,580,1422,1423,2237,2235,2236,2230,2238],"class_list":["post-8710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conoscenza","category-molle-a-filo","category-molle-di-compressione","tag-calcola-il-tasso-di-primavera","tag-calcola-la-costante-della-molla","tag-corpo-primaverile","tag-determinare-la-velocita-della-molla","tag-federkonstante-it","tag-festigkeitsnachweis-it","tag-indice-di-rigidezza","tag-legge-di-hookese","tag-molla-a-compressione-costante-della-molla","tag-molla-di-compressione-a-molla","tag-momento-di-torsione-primaverile","tag-tasso-di-coppia-della-molla","tag-viaggio-a-tariffa-primaverile"],"_links":{"self":[{"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/posts\/8710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/comments?post=8710"}],"version-history":[{"count":6,"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/posts\/8710\/revisions"}],"predecessor-version":[{"id":11498,"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/posts\/8710\/revisions\/11498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/media\/8719"}],"wp:attachment":[{"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/media?parent=8710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/categories?post=8710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.federnshop.com\/it\/wp-json\/wp\/v2\/tags?post=8710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}